{"id":743,"date":"2019-07-28T11:36:07","date_gmt":"2019-07-28T15:36:07","guid":{"rendered":"https:\/\/www.whelkgoods.com\/?page_id=743"},"modified":"2025-12-14T16:04:07","modified_gmt":"2025-12-14T21:04:07","slug":"accueil","status":"publish","type":"page","link":"https:\/\/whelkgoods.com\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"743\" class=\"elementor elementor-743 elementor-255\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2cd81 elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"b2cd81\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a9b5347\" data-id=\"3a9b5347\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53b9a4b elementor-widget elementor-widget-heading\" data-id=\"53b9a4b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Casquettes \u00e9coresponsables<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-119eca62 elementor-widget elementor-widget-heading\" data-id=\"119eca62\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Une visi\u00e8re \u00e0 impact r\u00e9duit sur l\u2019environnement<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ccd510b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ccd510b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-381a3fa\" data-id=\"381a3fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-731ba9bf elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"731ba9bf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/whelkgoods.com\/fr\/categorie-produit\/casquettes-blutech\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrir la collection<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-708e4a1\" data-id=\"708e4a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68f7ce8 elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"68f7ce8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/whelkgoods.com\/fr\/technologie-blutech\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus sur le Blutech<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-525bf093 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"525bf093\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36d6a3b3\" data-id=\"36d6a3b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65bd929d elementor-widget elementor-widget-heading\" data-id=\"65bd929d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Explore par style<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-468b6e09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"468b6e09\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-fc2ae8b\" data-id=\"fc2ae8b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e1c0f7 elementor-widget elementor-widget-image\" data-id=\"e1c0f7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/categorie-produit\/casquettes-blutech\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg\" class=\"attachment-medium size-medium wp-image-15806\" alt=\"\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-150x150.jpg 150w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-768x768.jpg 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-600x600.jpg 600w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-100x100.jpg 100w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e3aaab elementor-widget elementor-widget-heading\" data-id=\"5e3aaab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/whelkgoods.com\/fr\/categorie-produit\/casquettes-blutech\/\">Casquettes baseball<\/a><\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-ec74914\" data-id=\"ec74914\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cc7caf0 elementor-widget elementor-widget-image\" data-id=\"5cc7caf0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/whelkgoods.com\/product\/performance-cap\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/03\/Whelk-Performance-Cap-in-Peru-300x300.jpg\" class=\"attachment-medium size-medium wp-image-15335\" alt=\"\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/03\/Whelk-Performance-Cap-in-Peru-300x300.jpg 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/03\/Whelk-Performance-Cap-in-Peru-150x150.jpg 150w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/03\/Whelk-Performance-Cap-in-Peru-768x768.jpg 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/03\/Whelk-Performance-Cap-in-Peru-600x600.jpg 600w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/03\/Whelk-Performance-Cap-in-Peru-100x100.jpg 100w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/03\/Whelk-Performance-Cap-in-Peru.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e85e01c elementor-widget elementor-widget-heading\" data-id=\"4e85e01c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/whelkgoods.com\/product\/performance-cap\/\">Casquette de sport<\/a><\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4dbbf8b7\" data-id=\"4dbbf8b7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47bb39e6 elementor-widget elementor-widget-image\" data-id=\"47bb39e6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/produit\/chapeau-bob-classique\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2020\/05\/1-300x300.png\" class=\"attachment-medium size-medium wp-image-15763\" alt=\"\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2020\/05\/1-300x300.png 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2020\/05\/1-150x150.png 150w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2020\/05\/1-768x768.png 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2020\/05\/1-600x600.png 600w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2020\/05\/1-100x100.png 100w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2020\/05\/1.png 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18766bac elementor-widget elementor-widget-heading\" data-id=\"18766bac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/whelkgoods.com\/fr\/produit\/chapeau-bob-classique\/\">Chapeau bob<\/a><\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d6c8891\" data-id=\"d6c8891\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26d091d0 elementor-widget elementor-widget-image\" data-id=\"26d091d0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/categorie-produit\/tuques-fr\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/12\/Marl-Waffle-Beanies-300x300.jpg\" class=\"attachment-medium size-medium wp-image-17810\" alt=\"\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/12\/Marl-Waffle-Beanies-300x300.jpg 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/12\/Marl-Waffle-Beanies-150x150.jpg 150w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/12\/Marl-Waffle-Beanies-768x768.jpg 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/12\/Marl-Waffle-Beanies-600x600.jpg 600w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/12\/Marl-Waffle-Beanies-100x100.jpg 100w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/12\/Marl-Waffle-Beanies.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2317bdc9 elementor-widget elementor-widget-heading\" data-id=\"2317bdc9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/whelkgoods.com\/fr\/categorie-produit\/tuques-fr\/\">Tuques<\/a><\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36d3e74a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36d3e74a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5214b5d8\" data-id=\"5214b5d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-57c8687d elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57c8687d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-57f9cb0d\" data-id=\"57f9cb0d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b360790 elementor-widget elementor-widget-heading\" data-id=\"1b360790\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Moins de plastique, plus d\u2019impact<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a26ace4 elementor-widget elementor-widget-text-editor\" data-id=\"6a26ace4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Derri\u00e8re la plupart des casquettes se cache un secret : une visi\u00e8re en plastique qui se d\u00e9sint\u00e8gre en microplastiques. On a voulu faire mieux.<\/p><p>Voici la visi\u00e8re Blutech : con\u00e7ue pour durer toute une vie et pens\u00e9e comme une alternative durable aux visi\u00e8res traditionnelles.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44b7faaf elementor-align-center elementor-widget elementor-widget-button\" data-id=\"44b7faaf\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/whelkgoods.com\/fr\/technologie-blutech\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En apprendre plus sur le Blutech<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41191fe1\" data-id=\"41191fe1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23dcdaf7 elementor-widget-tablet__width-initial elementor-widget elementor-widget-image\" data-id=\"23dcdaf7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"613\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Blutech-Visor-Zoom-Cropped.png\" class=\"attachment-full size-full wp-image-17362\" alt=\"\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Blutech-Visor-Zoom-Cropped.png 1000w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Blutech-Visor-Zoom-Cropped-300x184.png 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Blutech-Visor-Zoom-Cropped-768x471.png 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Blutech-Visor-Zoom-Cropped-600x368.png 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-143e3200 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"143e3200\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35b1ce94\" data-id=\"35b1ce94\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-604a9985 elementor-widget elementor-widget-heading\" data-id=\"604a9985\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos casquettes vedettes<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bd4cebf elementor-grid-tablet-4 elementor-grid-4 elementor-grid-mobile-2 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"1bd4cebf\" data-element_type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"woocommerce columns-4 \">\t\t<ul class=\"products elementor-grid columns-4 tablet-columns-2 mobile-columns-2\">\n\t\t<li class=\"product type-product post-10455 status-publish first instock product_cat-casquettes product_cat-casquettes-blutech product_cat-chapeaux has-post-thumbnail taxable shipping-taxable purchasable product-type-variable has-default-attributes\">\n\t\t\t<div class=\"product-loop-wrapper\">\n\t\t<div class=\"product-loop-image-wrapper\">\t\t<div class=\"product-loop-action\"><\/div>\n\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/produit\/casquette-velo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">\t\t\t\t<span class=\"product-loop-hover-image\" style=\"background-image: url(https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Bike-Baby-Blue-600x600.png);\"><\/span>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Bike-600x600.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail product-loop-image\" alt=\"Image du produit\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Bike-600x600.png 600w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Bike-300x300.png 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Bike-150x150.png 150w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Bike-768x768.png 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Bike-100x100.png 100w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Bike.png 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/div><div class=\"product-loop-content text-center\">\t\t<h2 class=\"woocommerce-loop-product__title\">\n\t\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/produit\/casquette-velo\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Casquette V\u00e9lo<\/a>\t\t<\/h2>\n\t\t\t\t\t<div class=\"swatch-list variation-circle\"><span class=\"swatch swatch-color selected swatch-blue-pale\" data-slug=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Bike-600x600.png\" style=\"background-color: #a9baca\"><span class=\"swatch-tooltip\">Bleu ciel<\/span><\/span><span class=\"swatch swatch-color swatch-kaki\" data-slug=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Bike-Beige-600x600.png\" style=\"background-color: #aa8f72\"><span class=\"swatch-tooltip\">Beige sable<\/span><\/span><\/div>\n\t\t\t<div class=\"product-loop-meta no-transform\"><div class=\"animated-meta\">\t\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\">35.00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">$ CAD<\/span><\/span><\/span>\n\t\t\t<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:10455,&quot;item_id&quot;:10455,&quot;item_name&quot;:&quot;Casquette V\\u00e9lo&quot;,&quot;sku&quot;:&quot;CAP-BIKE&quot;,&quot;price&quot;:35,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Casquettes Blutech&quot;,&quot;id&quot;:10455,&quot;productlink&quot;:&quot;https:\\\/\\\/whelkgoods.com\\\/fr\\\/produit\\\/casquette-velo\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:1,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/div><\/div><\/div>\t\t<\/div>\n\t\t<\/li>\n<li class=\"product type-product post-11204 status-publish instock product_cat-casquettes product_cat-casquettes-blutech product_cat-chapeaux has-post-thumbnail taxable shipping-taxable purchasable product-type-variable has-default-attributes\">\n\t\t\t<div class=\"product-loop-wrapper\">\n\t\t<div class=\"product-loop-image-wrapper\">\t\t<div class=\"product-loop-action\"><\/div>\n\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/produit\/casquette-epinette\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">\t\t\t\t<span class=\"product-loop-hover-image\" style=\"background-image: url(https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Spruce-600x600.png);\"><\/span>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Spruce-600x600.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail product-loop-image\" alt=\"Image du produit\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Spruce-600x600.png 600w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Spruce-300x300.png 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Spruce-150x150.png 150w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Spruce-768x768.png 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Spruce-100x100.png 100w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Spruce.png 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/div><div class=\"product-loop-content text-center\">\t\t<h2 class=\"woocommerce-loop-product__title\">\n\t\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/produit\/casquette-epinette\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Casquette \u00c9pinette<\/a>\t\t<\/h2>\n\t\t\t\t\t<div class=\"swatch-list variation-circle\"><span class=\"swatch swatch-color selected swatch-vert\" data-slug=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Spruce-600x600.png\" style=\"background-color: #1f462e\"><span class=\"swatch-tooltip\">Vert for\u00eat<\/span><\/span><\/div>\n\t\t\t<div class=\"product-loop-meta no-transform\"><div class=\"animated-meta\">\t\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\">35.00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">$ CAD<\/span><\/span><\/span>\n\t\t\t<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:11204,&quot;item_id&quot;:11204,&quot;item_name&quot;:&quot;Casquette \\u00c9pinette&quot;,&quot;sku&quot;:&quot;CAP-SPR&quot;,&quot;price&quot;:35,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Casquettes Blutech&quot;,&quot;id&quot;:11204,&quot;productlink&quot;:&quot;https:\\\/\\\/whelkgoods.com\\\/fr\\\/produit\\\/casquette-epinette\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:2,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/div><\/div><\/div>\t\t<\/div>\n\t\t<\/li>\n<li class=\"product type-product post-10499 status-publish instock product_cat-casquettes product_cat-casquettes-blutech product_cat-chapeaux has-post-thumbnail taxable shipping-taxable purchasable product-type-variable has-default-attributes\">\n\t\t\t<div class=\"product-loop-wrapper\">\n\t\t<div class=\"product-loop-image-wrapper\">\t\t<div class=\"product-loop-action\"><\/div>\n\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/produit\/casquette-coucher-du-soleil\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">\t\t\t\t<span class=\"product-loop-hover-image\" style=\"background-image: url(https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Sunset-Beige-600x600.png);\"><\/span>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Sunset-600x600.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail product-loop-image\" alt=\"Image du produit\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Sunset-600x600.png 600w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Sunset-300x300.png 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Sunset-150x150.png 150w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Sunset-768x768.png 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Sunset-100x100.png 100w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Sunset.png 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/div><div class=\"product-loop-content text-center\">\t\t<h2 class=\"woocommerce-loop-product__title\">\n\t\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/produit\/casquette-coucher-du-soleil\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Casquette coucher du soleil<\/a>\t\t<\/h2>\n\t\t\t\t\t<div class=\"swatch-list variation-circle\"><span class=\"swatch swatch-color selected swatch-kaki unavailable\" data-slug=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Sunset-600x600.png\" style=\"background-color: #aa8f72\"><span class=\"swatch-tooltip\">Beige sable<\/span><\/span><span class=\"swatch swatch-color swatch-noire\" data-slug=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Sunset-Black-600x600.png\" style=\"background-color: #000000\"><span class=\"swatch-tooltip\">Noir orque<\/span><\/span><\/div>\n\t\t\t<div class=\"product-loop-meta no-transform\"><div class=\"animated-meta\">\t\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\">35.00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">$ CAD<\/span><\/span><\/span>\n\t\t\t<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:10499,&quot;item_id&quot;:10499,&quot;item_name&quot;:&quot;Casquette coucher du soleil&quot;,&quot;sku&quot;:&quot;CAP-SUN&quot;,&quot;price&quot;:35,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Casquettes Blutech&quot;,&quot;id&quot;:10499,&quot;productlink&quot;:&quot;https:\\\/\\\/whelkgoods.com\\\/fr\\\/produit\\\/casquette-coucher-du-soleil\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:3,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/div><\/div><\/div>\t\t<\/div>\n\t\t<\/li>\n<li class=\"product type-product post-15706 status-publish last instock product_cat-casquettes product_cat-casquettes-blutech product_cat-chapeaux product_cat-collection-canada has-post-thumbnail taxable shipping-taxable purchasable product-type-variable has-default-attributes\">\n\t\t\t<div class=\"product-loop-wrapper\">\n\t\t<div class=\"product-loop-image-wrapper\">\t\t<div class=\"product-loop-action\"><\/div>\n\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/produit\/casquette-huard\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">\t\t\t\t<span class=\"product-loop-hover-image\" style=\"background-image: url(https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/Loon-600x600.png);\"><\/span>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Loon-600x600.png\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail product-loop-image\" alt=\"Image du produit\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Loon-600x600.png 600w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Loon-300x300.png 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Loon-150x150.png 150w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Loon-768x768.png 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Loon-100x100.png 100w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2025\/03\/MAIN-Loon.png 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/div><div class=\"product-loop-content text-center\">\t\t<h2 class=\"woocommerce-loop-product__title\">\n\t\t\t<a href=\"https:\/\/whelkgoods.com\/fr\/produit\/casquette-huard\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\">Casquette huard<\/a>\t\t<\/h2>\n\t\t\t\t\t<div class=\"swatch-list variation-circle\"><span class=\"swatch swatch-color selected swatch-beige-sable-vert-foret\" data-slug=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Whelk-Loon-Cap-600x600.png\" style=\"background-color: #cbb4a6\"><span class=\"swatch-tooltip\">Beige pierre &amp; vert for\u00eat<\/span><\/span><\/div>\n\t\t\t<div class=\"product-loop-meta no-transform\"><div class=\"animated-meta\">\t\t\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\">35.00&nbsp;<span class=\"woocommerce-Price-currencySymbol\">$ CAD<\/span><\/span><\/span>\n\t\t\t<span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:15706,&quot;item_id&quot;:15706,&quot;item_name&quot;:&quot;Casquette huard&quot;,&quot;sku&quot;:15706,&quot;price&quot;:35,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Casquettes Blutech&quot;,&quot;id&quot;:15706,&quot;productlink&quot;:&quot;https:\\\/\\\/whelkgoods.com\\\/fr\\\/produit\\\/casquette-huard\\\/&quot;,&quot;item_list_name&quot;:&quot;Liste g\\u00e9n\\u00e9rale des produits&quot;,&quot;index&quot;:4,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span><\/div><\/div><\/div>\t\t<\/div>\n\t\t<\/li>\n<\/ul>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-434552dd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"434552dd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/whelkgoods.com\/fr\/categorie-produit\/casquettes-blutech\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Explorer tous nos chapeaux<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-397a0757 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"397a0757\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fb745c2\" data-id=\"3fb745c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3edadb2 elementor-widget elementor-widget-heading\" data-id=\"3edadb2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Tel que vu dans<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-21d10687 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21d10687\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-459f943b\" data-id=\"459f943b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e1a5e4f elementor-widget elementor-widget-image\" data-id=\"7e1a5e4f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/elementor\/thumbs\/2012_logo_for_La_Presse_newspaper.svg-qugecu787ifebkca94hgri03mm3i37vspqj9gomt48.png\" title=\"2012_logo_for_La_Presse_newspaper.svg\" alt=\"2012_logo_for_La_Presse_newspaper.svg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-406981e8\" data-id=\"406981e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67b7cc75 elementor-widget elementor-widget-image\" data-id=\"67b7cc75\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/elementor\/thumbs\/La-Tribune-Logo-qugeh9zt39w2pzawdgnebv6mxv3m4p4fmuzh3y0zoi.png\" title=\"La Tribune Logo\" alt=\"La Tribune Logo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-49e5a5b4\" data-id=\"49e5a5b4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66049554 elementor-widget elementor-widget-image\" data-id=\"66049554\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/09\/logo_1077_2021_inversed_default.svg\" title=\"logo_1077_2021_inversed_default\" alt=\"logo_1077_2021_inversed_default\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-0422a99\" data-id=\"0422a99\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf03cf9 elementor-widget elementor-widget-image\" data-id=\"bf03cf9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/elementor\/thumbs\/Info_du_Nord_MT_Renv-r87vra2n4nvrhi7t3dj0g2h1k0wmsdcyyoga4lohb6.png\" title=\"Info_du_Nord_MT_Renv\" alt=\"Info_du_Nord_MT_Renv\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-648d067b\" data-id=\"648d067b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fe1f407 elementor-widget elementor-widget-image\" data-id=\"6fe1f407\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/elementor\/thumbs\/Impactful-Ninja-Logo-qugenoa8oskfddwayljym0tazn8yz539pshxlekuy6.png\" title=\"Impactful-Ninja-Logo\" alt=\"Impactful-Ninja-Logo\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Impactful Ninja<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-20433396 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"20433396\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6f59b690\" data-id=\"6f59b690\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-512ddda3 elementor-widget elementor-widget-heading\" data-id=\"512ddda3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ce que nous d\u00e9fendons<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6087332a elementor-widget elementor-widget-text-editor\" data-id=\"6087332a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tNotre mission est de favoriser l&rsquo;adoption de la mode durable en proposant des accessoires \u00e9thiquement con\u00e7us pour durer une vie enti\u00e8re.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20742301 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"20742301\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/whelkgoods.com\/fr\/a-propos\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00c0 l'int\u00e9reur de Whelk<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4e00943a\" data-id=\"4e00943a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a64c871 elementor-widget elementor-widget-image\" data-id=\"2a64c871\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Whelk-Mission-Statement-600x600.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail wp-image-15832\" alt=\"\" srcset=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Whelk-Mission-Statement-600x600.jpg 600w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Whelk-Mission-Statement-300x300.jpg 300w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Whelk-Mission-Statement-150x150.jpg 150w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Whelk-Mission-Statement-768x768.jpg 768w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Whelk-Mission-Statement-100x100.jpg 100w, https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Whelk-Mission-Statement.jpg 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">@evedbs_ au Qu\u00e9bec, Canada<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Casquettes \u00e9coresponsables Une visi\u00e8re \u00e0 impact r\u00e9duit sur l\u2019environnement D\u00e9couvrir la collection En savoir plus sur le Blutech Explore par style Casquettes baseball Casquette de sport Chapeau bob Tuques Moins de plastique, plus d\u2019impact Derri\u00e8re la plupart des casquettes se cache un secret : une visi\u00e8re en plastique qui se d\u00e9sint\u00e8gre en microplastiques. On a voulu faire mieux. Voici la visi\u00e8re Blutech : con\u00e7ue pour durer toute une vie et pens\u00e9e comme une alternative durable aux visi\u00e8res traditionnelles. En apprendre plus sur le Blutech Nos casquettes vedettes Explorer tous nos chapeaux Tel que vu dans Impactful Ninja Ce que nous&#8230;<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-743","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Whelk | Marque qu\u00e9b\u00e9coise - Casquettes \u00e9coresponsables<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre produit vedette : la casquette avec visi\u00e8re biod\u00e9gradable. Explorez nos tuques, casquettes, chapeau bob et bien plus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/whelkgoods.com\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Whelk | Marque qu\u00e9b\u00e9coise - Casquettes \u00e9coresponsables\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre produit vedette : la casquette avec visi\u00e8re biod\u00e9gradable. Explorez nos tuques, casquettes, chapeau bob et bien plus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/whelkgoods.com\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Whelk | Marque qu\u00e9b\u00e9coise\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-14T21:04:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/whelkgoods.com\/fr\/\",\"url\":\"https:\/\/whelkgoods.com\/fr\/\",\"name\":\"Whelk | Marque qu\u00e9b\u00e9coise - Casquettes \u00e9coresponsables\",\"isPartOf\":{\"@id\":\"https:\/\/whelkgoods.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/whelkgoods.com\/fr\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/whelkgoods.com\/fr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg\",\"datePublished\":\"2019-07-28T15:36:07+00:00\",\"dateModified\":\"2025-12-14T21:04:07+00:00\",\"description\":\"D\u00e9couvrez notre produit vedette : la casquette avec visi\u00e8re biod\u00e9gradable. Explorez nos tuques, casquettes, chapeau bob et bien plus.\",\"breadcrumb\":{\"@id\":\"https:\/\/whelkgoods.com\/fr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/whelkgoods.com\/fr\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/whelkgoods.com\/fr\/#primaryimage\",\"url\":\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg\",\"contentUrl\":\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/whelkgoods.com\/fr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/whelkgoods.com\/fr\/accueil\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accueil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/whelkgoods.com\/fr\/#website\",\"url\":\"https:\/\/whelkgoods.com\/fr\/\",\"name\":\"Whelk | Marque qu\u00e9b\u00e9coise\",\"description\":\"Casquettes et tuques \u00e9coresponsables\",\"publisher\":{\"@id\":\"https:\/\/whelkgoods.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/whelkgoods.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/whelkgoods.com\/fr\/#organization\",\"name\":\"Whelk | Marque qu\u00e9b\u00e9coise\",\"url\":\"https:\/\/whelkgoods.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/whelkgoods.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2023\/08\/Whelk-Goods-Logo.png\",\"contentUrl\":\"https:\/\/whelkgoods.com\/wp-content\/uploads\/2023\/08\/Whelk-Goods-Logo.png\",\"width\":750,\"height\":253,\"caption\":\"Whelk | Marque qu\u00e9b\u00e9coise\"},\"image\":{\"@id\":\"https:\/\/whelkgoods.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Whelk | Marque qu\u00e9b\u00e9coise - Casquettes \u00e9coresponsables","description":"D\u00e9couvrez notre produit vedette : la casquette avec visi\u00e8re biod\u00e9gradable. Explorez nos tuques, casquettes, chapeau bob et bien plus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/whelkgoods.com\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Whelk | Marque qu\u00e9b\u00e9coise - Casquettes \u00e9coresponsables","og_description":"D\u00e9couvrez notre produit vedette : la casquette avec visi\u00e8re biod\u00e9gradable. Explorez nos tuques, casquettes, chapeau bob et bien plus.","og_url":"https:\/\/whelkgoods.com\/fr\/","og_site_name":"Whelk | Marque qu\u00e9b\u00e9coise","article_modified_time":"2025-12-14T21:04:07+00:00","og_image":[{"url":"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/whelkgoods.com\/fr\/","url":"https:\/\/whelkgoods.com\/fr\/","name":"Whelk | Marque qu\u00e9b\u00e9coise - Casquettes \u00e9coresponsables","isPartOf":{"@id":"https:\/\/whelkgoods.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/whelkgoods.com\/fr\/#primaryimage"},"image":{"@id":"https:\/\/whelkgoods.com\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg","datePublished":"2019-07-28T15:36:07+00:00","dateModified":"2025-12-14T21:04:07+00:00","description":"D\u00e9couvrez notre produit vedette : la casquette avec visi\u00e8re biod\u00e9gradable. Explorez nos tuques, casquettes, chapeau bob et bien plus.","breadcrumb":{"@id":"https:\/\/whelkgoods.com\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/whelkgoods.com\/fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/whelkgoods.com\/fr\/#primaryimage","url":"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg","contentUrl":"https:\/\/whelkgoods.com\/wp-content\/uploads\/2024\/04\/Atlantic-Puffin-Cap-300x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/whelkgoods.com\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/whelkgoods.com\/fr\/accueil\/"},{"@type":"ListItem","position":2,"name":"Accueil"}]},{"@type":"WebSite","@id":"https:\/\/whelkgoods.com\/fr\/#website","url":"https:\/\/whelkgoods.com\/fr\/","name":"Whelk | Marque qu\u00e9b\u00e9coise","description":"Casquettes et tuques \u00e9coresponsables","publisher":{"@id":"https:\/\/whelkgoods.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/whelkgoods.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/whelkgoods.com\/fr\/#organization","name":"Whelk | Marque qu\u00e9b\u00e9coise","url":"https:\/\/whelkgoods.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/whelkgoods.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/whelkgoods.com\/wp-content\/uploads\/2023\/08\/Whelk-Goods-Logo.png","contentUrl":"https:\/\/whelkgoods.com\/wp-content\/uploads\/2023\/08\/Whelk-Goods-Logo.png","width":750,"height":253,"caption":"Whelk | Marque qu\u00e9b\u00e9coise"},"image":{"@id":"https:\/\/whelkgoods.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/whelkgoods.com\/fr\/wp-json\/wp\/v2\/pages\/743"}],"collection":[{"href":"https:\/\/whelkgoods.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whelkgoods.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whelkgoods.com\/fr\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/whelkgoods.com\/fr\/wp-json\/wp\/v2\/comments?post=743"}],"version-history":[{"count":370,"href":"https:\/\/whelkgoods.com\/fr\/wp-json\/wp\/v2\/pages\/743\/revisions"}],"predecessor-version":[{"id":17830,"href":"https:\/\/whelkgoods.com\/fr\/wp-json\/wp\/v2\/pages\/743\/revisions\/17830"}],"wp:attachment":[{"href":"https:\/\/whelkgoods.com\/fr\/wp-json\/wp\/v2\/media?parent=743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}